{"id":30660,"date":"2022-10-02T02:39:01","date_gmt":"2022-10-02T02:39:01","guid":{"rendered":"https:\/\/mktdev.hostfully.com\/property-management-software\/integrations\/dtravel\/"},"modified":"2026-03-29T20:33:54","modified_gmt":"2026-03-29T20:33:54","slug":"dtravel","status":"publish","type":"integrations","link":"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/","title":{"rendered":"Dtravel"},"excerpt":{"rendered":"<p>Aumente as reservas e a rentabilidade criando um site de reservas diretas com um design apelativo e otimizado para a convers\u00e3o em minutos.<\/p>\n","protected":false},"menu_order":934,"template":"","integration-categories":[1490],"class_list":["post-30660","integrations","type-integrations","status-publish","hentry","integration-categories-canais-de-distribuicao"],"integration_subtitle":"Torne-se um profissional em reservas diretas e concorra com as OTAs","integration_logo":"https:\/\/www.hostfully.com\/wp-content\/uploads\/2025\/11\/Dtravel_Logo_black-James-4-scaled.png","integration_icon":"https:\/\/www.hostfully.com\/wp-content\/uploads\/2022\/10\/D-Logo-James-150x150-1.png","integration_url":"https:\/\/www.dtravel.com\/","integration_custom_label_text":"","_yoast_wpseo_title":"Integra\u00e7\u00e3o Dtravel - Ven\u00e7a nas reservas diretas | Plataforma de Gest\u00e3o de Propriedades Hostfully","_yoast_wpseo_metadesc":"Aumente as reservas e a rentabilidade criando um site de reservas diretas com um design apelativo e otimizado para a convers\u00e3o em minutos.","integration_desc":"<p>A Dtravel tem como objetivo acelerar a ado\u00e7\u00e3o global de reservas diretas, facilitando a qualquer pessoa reservar alojamentos de f\u00e9rias diretamente, em vez de ter de recorrer a uma ag\u00eancia de viagens online (OTA). Com o Dtravel Direct, os gestores de propriedades podem aumentar as reservas e a rentabilidade criando um site de reservas diretas com um design apelativo e otimizado para a convers\u00e3o em minutos. <\/p>\n","integration_featured":false,"integration_custom_label":false,"coming-soon":true,"integrations-benefits":["Crie, personalize e lance o site em minutos","Sem taxas recorrentes nem experi\u00eancia em programa\u00e7\u00e3o necess\u00e1rias","Estabele\u00e7a uma presen\u00e7a online fi\u00e1vel e profissional","Controlo total sobre os seus termos e pol\u00edticas de reserva","Aumente o valor m\u00e9dio da reserva"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Integra\u00e7\u00e3o Dtravel - Ven\u00e7a nas reservas diretas | Plataforma de Gest\u00e3o de Propriedades Hostfully<\/title>\n<meta name=\"description\" content=\"Aumente as reservas e a rentabilidade criando um site de reservas diretas com um design apelativo e otimizado para a convers\u00e3o em minutos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dtravel\" \/>\n<meta property=\"og:description\" content=\"Aumente as reservas e a rentabilidade criando um site de reservas diretas com um design apelativo e otimizado para a convers\u00e3o em minutos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/\" \/>\n<meta property=\"og:site_name\" content=\"Hostfully\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hostfully\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-29T20:33:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hostfully.com\/wp-content\/uploads\/2022\/09\/Group-4846.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@hostfully\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/software-de-gestao-de-propriedades\\\/integracoes\\\/dtravel\\\/\",\"url\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/software-de-gestao-de-propriedades\\\/integracoes\\\/dtravel\\\/\",\"name\":\"Integra\u00e7\u00e3o Dtravel - Ven\u00e7a nas reservas diretas | Plataforma de Gest\u00e3o de Propriedades Hostfully\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/software-de-gestao-de-propriedades\\\/integracoes\\\/dtravel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/software-de-gestao-de-propriedades\\\/integracoes\\\/dtravel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hostfully.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Group-4846.svg\",\"datePublished\":\"2022-10-02T02:39:01+00:00\",\"dateModified\":\"2026-03-29T20:33:54+00:00\",\"description\":\"Aumente as reservas e a rentabilidade criando um site de reservas diretas com um design apelativo e otimizado para a convers\u00e3o em minutos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/software-de-gestao-de-propriedades\\\/integracoes\\\/dtravel\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/software-de-gestao-de-propriedades\\\/integracoes\\\/dtravel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/software-de-gestao-de-propriedades\\\/integracoes\\\/dtravel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hostfully.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Group-4846.svg\",\"contentUrl\":\"https:\\\/\\\/www.hostfully.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Group-4846.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/software-de-gestao-de-propriedades\\\/integracoes\\\/dtravel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Integra\u00e7\u00f5es\",\"item\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/software-de-gestao-de-propriedades\\\/integracoes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dtravel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/\",\"name\":\"Hostfully\",\"description\":\"Award Winning Vacation Rental Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/#organization\",\"name\":\"Hostfully\",\"url\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hostfully.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Hostfully_bluecircle_isotype_R-.png\",\"contentUrl\":\"https:\\\/\\\/www.hostfully.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Hostfully_bluecircle_isotype_R-.png\",\"width\":321,\"height\":321,\"caption\":\"Hostfully\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostfully.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hostfully\",\"https:\\\/\\\/x.com\\\/hostfully\",\"https:\\\/\\\/www.instagram.com\\\/hostfully_\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Hostfully\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hostfully-inc-\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Integra\u00e7\u00e3o Dtravel - Ven\u00e7a nas reservas diretas | Plataforma de Gest\u00e3o de Propriedades Hostfully","description":"Aumente as reservas e a rentabilidade criando um site de reservas diretas com um design apelativo e otimizado para a convers\u00e3o em minutos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/","og_locale":"pt_PT","og_type":"article","og_title":"Dtravel","og_description":"Aumente as reservas e a rentabilidade criando um site de reservas diretas com um design apelativo e otimizado para a convers\u00e3o em minutos.","og_url":"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/","og_site_name":"Hostfully","article_publisher":"https:\/\/www.facebook.com\/hostfully","article_modified_time":"2026-03-29T20:33:54+00:00","og_image":[{"url":"https:\/\/www.hostfully.com\/wp-content\/uploads\/2022\/09\/Group-4846.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@hostfully","twitter_misc":{"Tempo estimado de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/","url":"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/","name":"Integra\u00e7\u00e3o Dtravel - Ven\u00e7a nas reservas diretas | Plataforma de Gest\u00e3o de Propriedades Hostfully","isPartOf":{"@id":"https:\/\/www.hostfully.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/#primaryimage"},"image":{"@id":"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hostfully.com\/wp-content\/uploads\/2022\/09\/Group-4846.svg","datePublished":"2022-10-02T02:39:01+00:00","dateModified":"2026-03-29T20:33:54+00:00","description":"Aumente as reservas e a rentabilidade criando um site de reservas diretas com um design apelativo e otimizado para a convers\u00e3o em minutos.","breadcrumb":{"@id":"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/#primaryimage","url":"https:\/\/www.hostfully.com\/wp-content\/uploads\/2022\/09\/Group-4846.svg","contentUrl":"https:\/\/www.hostfully.com\/wp-content\/uploads\/2022\/09\/Group-4846.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/dtravel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hostfully.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Integra\u00e7\u00f5es","item":"https:\/\/www.hostfully.com\/pt-pt\/software-de-gestao-de-propriedades\/integracoes\/"},{"@type":"ListItem","position":3,"name":"Dtravel"}]},{"@type":"WebSite","@id":"https:\/\/www.hostfully.com\/pt-pt\/#website","url":"https:\/\/www.hostfully.com\/pt-pt\/","name":"Hostfully","description":"Award Winning Vacation Rental Software","publisher":{"@id":"https:\/\/www.hostfully.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hostfully.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.hostfully.com\/pt-pt\/#organization","name":"Hostfully","url":"https:\/\/www.hostfully.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.hostfully.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.hostfully.com\/wp-content\/uploads\/2025\/08\/Hostfully_bluecircle_isotype_R-.png","contentUrl":"https:\/\/www.hostfully.com\/wp-content\/uploads\/2025\/08\/Hostfully_bluecircle_isotype_R-.png","width":321,"height":321,"caption":"Hostfully"},"image":{"@id":"https:\/\/www.hostfully.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hostfully","https:\/\/x.com\/hostfully","https:\/\/www.instagram.com\/hostfully_\/","https:\/\/www.youtube.com\/c\/Hostfully","https:\/\/www.linkedin.com\/company\/hostfully-inc-\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hostfully.com\/pt-pt\/wp-json\/wp\/v2\/integrations\/30660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostfully.com\/pt-pt\/wp-json\/wp\/v2\/integrations"}],"about":[{"href":"https:\/\/www.hostfully.com\/pt-pt\/wp-json\/wp\/v2\/types\/integrations"}],"wp:attachment":[{"href":"https:\/\/www.hostfully.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=30660"}],"wp:term":[{"taxonomy":"integration-categories","embeddable":true,"href":"https:\/\/www.hostfully.com\/pt-pt\/wp-json\/wp\/v2\/integration-categories?post=30660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}